{"id":1585,"date":"2015-04-26T18:51:24","date_gmt":"2015-04-26T16:51:24","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=1585"},"modified":"2015-04-26T18:51:24","modified_gmt":"2015-04-26T16:51:24","slug":"pictures-from-the-remerschen-wildlife-walk","status":"publish","type":"post","link":"http:\/\/english.ciel.lu\/de\/pictures-from-the-remerschen-wildlife-walk\/","title":{"rendered":"Bilder vom Remerschen Wildlife Walk"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1586\" alt=\"Foto von Dirk Westermann\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/2015-04-25-10-35-41_600px.jpg?resize=600%2C338\" width=\"600\" height=\"338\" \/><\/p>\n<p>Am vergangenen Samstagmorgen organisierten Jocelyn und DirkW f\u00fcr interessierte CIEL-Mitglieder einen Fotospaziergang rund um die Remerschen Vogelseen. Der Regen h\u00f6rte ganz kurz nach unserer Ankunft auf, und die acht Fotografen machten mehr als zwei Stunden lang einen sch\u00f6nen Spaziergang um die Seen, entdeckten verschiedene \u2013 manchmal versteckte \u2013 Fotospots, praktizierten Wildtierfotografie mit kleinen und gr\u00f6\u00dferen V\u00f6geln in der Gegend und diskutierten \u00fcber das Leben und diese Art von Fotografie. Anschlie\u00dfend \u00fcbernachteten einige Mitglieder in der modernen Jugendherberge in Remerschen f\u00fcr ein Drei-G\u00e4nge-Mittagessen, tauschten ihre Erfahrungen aus und schauten sich ihre Fotoergebnisse an. Insgesamt hatten wir eine wirklich gute Zeit zusammen, die - abgesehen von einem Sonnenschirm, der in die Freiheit ins tiefe Wasser entkam - uns einige neue Ansichten und eine sch\u00f6ne Erinnerung gab ...<\/p>\n<p>[Nggallery-ID=63]<\/p>","protected":false},"excerpt":{"rendered":"<p>Am vergangenen Samstagmorgen organisierten Jocelyn und DirkW einen Fotospaziergang rund um die Remerschen Vogelseen [...]<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[142,150,172,185,197],"class_list":["post-1585","post","type-post","status-publish","format-standard","hentry","category-club-news","tag-nature","tag-outing","tag-remerschen","tag-sortie","tag-vie-du-club"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/1585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/comments?post=1585"}],"version-history":[{"count":0,"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/1585\/revisions"}],"wp:attachment":[{"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/media?parent=1585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/categories?post=1585"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/tags?post=1585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}