{"id":5,"count":9,"description":"","link":"http:\/\/english.ciel.lu\/it\/category\/training\/","name":"Formation","slug":"training","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}