{"id":3451,"date":"2025-02-07T11:07:39","date_gmt":"2025-02-07T10:07:39","guid":{"rendered":"http:\/\/english.ciel.lu\/?p=3451"},"modified":"2025-02-07T11:07:39","modified_gmt":"2025-02-07T10:07:39","slug":"portraits-of-women","status":"publish","type":"post","link":"http:\/\/english.ciel.lu\/it\/portraits-of-women\/","title":{"rendered":"Ritratti di donne"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Questa mostra presenta ritratti di donne che lavorano nella protezione del patrimonio nelle regioni di conflitto, post-conflitto e crisi. Oggi, molti architetti, archeologi, custodi del sito, curatori di musei, storici dell'arte, restauratori e artigiani stanno lavorando sul terreno, spesso in contesti complicati, per salvaguardare monumenti, siti, musei, luoghi di culto o collezioni minacciate da guerre, cambiamenti climatici o disastri naturali. In occasione della Giornata internazionale della donna, l'Alleanza internazionale per la protezione del patrimonio (ALIPH) e la Commissione lussemburghese per l'UNESCO celebrano queste donne talentuose e coraggiose, custodi della nostra memoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Creato nel 2017 a Ginevra, ALIPH \u00e8 il principale fondo mondiale dedicato esclusivamente alla protezione o alla riabilitazione del patrimonio in situazioni di crisi. Si tratta di un partenariato pubblico-privato che riunisce otto paesi e tre donatori privati. Ad oggi, ALIPH ha sostenuto quasi 500 progetti in oltre 37 paesi, finanziando iniziative concrete realizzate sul campo, mano nella mano con partner locali, autorit\u00e0 e comunit\u00e0. Attraverso la protezione del patrimonio, ALIPH mira a contribuire alla costruzione della pace e allo sviluppo sostenibile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Granducato di Lussemburgo \u00e8 uno dei membri fondatori di ALIPH.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-neim-nster wp-block-embed-neim-nster\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mQMuLJpVVR\"><a href=\"https:\/\/www.neimenster.lu\/evenements\/portraits-de-femmes\/\">Portraits de femmes<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u201cPortraits de femmes\u201d \u2014 neim\u00ebnster\" src=\"https:\/\/www.neimenster.lu\/evenements\/portraits-de-femmes\/embed\/#?secret=Few5xprQJA#?secret=mQMuLJpVVR\" data-secret=\"mQMuLJpVVR\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Questa mostra presenta ritratti di donne che lavorano nella protezione del patrimonio in situazioni di conflitto, post-conflitto e crisi.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,4,7],"tags":[65,146,162],"class_list":["post-3451","post","type-post","status-publish","format-standard","hentry","category-blog","category-photo-expo","category-photo-news","tag-exposition","tag-news","tag-photos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts\/3451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/comments?post=3451"}],"version-history":[{"count":1,"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts\/3451\/revisions"}],"predecessor-version":[{"id":3452,"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts\/3451\/revisions\/3452"}],"wp:attachment":[{"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/media?parent=3451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/categories?post=3451"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/tags?post=3451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}