{"id":2989,"date":"2023-09-28T19:46:46","date_gmt":"2023-09-28T17:46:46","guid":{"rendered":"https:\/\/www.ciel.lu\/?p=2989"},"modified":"2023-09-28T19:46:46","modified_gmt":"2023-09-28T17:46:46","slug":"exhibition-adaptations-organised-by-cineast","status":"publish","type":"post","link":"http:\/\/english.ciel.lu\/pt\/exhibition-adaptations-organised-by-cineast\/","title":{"rendered":"Expo: \u00abAdapta\u00e7\u00e3o\u00bb organizada pela CinEast"},"content":{"rendered":"<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Convidamo-lo(a) a visitar a exposi\u00e7\u00e3o \u00ab<strong>Adapta\u00e7\u00f5es\u00bb<\/strong> em <strong>WED 4 DE OUTUBRO \u00e0s 18.30<\/strong> (<em>entrada gratuita<\/em>)<\/td><\/tr><tr><td><img data-recalc-dims=\"1\" decoding=\"async\"   alt=\"\" src=\"https:\/\/i0.wp.com\/mcusercontent.com\/373994ade2001bf8284e937f5\/images\/623fc7a6-c4ec-fcf2-5462-fba4679ecae9.jpg?w=564&#038;ssl=1\"\/><\/td><\/tr><tr><td>A exposi\u00e7\u00e3o de fotografia \u00ab<strong>Adapta\u00e7\u00f5es<\/strong>\u2019 apresentada nos Salles vout\u00e9es em Neim\u00ebnster apresenta uma reflex\u00e3o visual sobre o tema principal do festival, explorando os ajustamentos profundos exigidos por algumas das transforma\u00e7\u00f5es mais significativas que as nossas sociedades e a humanidade enfrentam atualmente.<br \/>A adapta\u00e7\u00e3o \u00e0s consequ\u00eancias da atual guerra na Ucr\u00e2nia, evidentemente, aos enormes e m\u00faltiplos desafios colocados pelas altera\u00e7\u00f5es clim\u00e1ticas, mas tamb\u00e9m a um ambiente marcado pelo aumento das migra\u00e7\u00f5es e pela r\u00e1pida evolu\u00e7\u00e3o tecnol\u00f3gica.<br \/>Uma das perspectivas que guiou o curador, <strong>Marta Szyma\u0144ska<\/strong>, na sua escolha de projetos fotogr\u00e1ficos foi encarar as adapta\u00e7\u00f5es n\u00e3o s\u00f3 como mudan\u00e7as for\u00e7adas impostas por um grande desafio, mas tamb\u00e9m \u2013 pelo menos em alguns casos \u2013 como solu\u00e7\u00f5es criativas para novas circunst\u00e2ncias, impulsionando-nos para a frente.<br \/><em>No passado, a humanidade muito raramente teve que se adaptar a mudan\u00e7as radicais dentro do espa\u00e7o de uma \u00fanica vida ou mesmo gera\u00e7\u00e3o. N\u00e3o h\u00e1 d\u00favida de que estamos actualmente a viver uma taxa de mudan\u00e7a sem precedentes em muitas \u00e1reas, que est\u00e1 a ter um impacto irrevers\u00edvel no mundo que conhecemos e nas formas como nos habitu\u00e1mos a lidar com ele. Estes m\u00e9todos n\u00e3o s\u00e3o mais eficazes ou tornaram-se totalmente desatualizados. A capacidade de se adaptar a condi\u00e7\u00f5es t\u00e3o rapidamente mut\u00e1veis parece ser uma das caracter\u00edsticas humanas mais importantes, se n\u00e3o a mais importante, tanto para os indiv\u00edduos como para as sociedades. Os efeitos irrevers\u00edveis das altera\u00e7\u00f5es clim\u00e1ticas, das altera\u00e7\u00f5es demogr\u00e1ficas, incluindo a migra\u00e7\u00e3o e o envelhecimento da popula\u00e7\u00e3o, da guerra, das viola\u00e7\u00f5es dos direitos humanos, da revolu\u00e7\u00e3o tecnol\u00f3gica, incluindo a intelig\u00eancia artificial, e o seu impacto no mercado de trabalho, nos governos autocr\u00e1ticos e na ideologia do crescimento constante que conduz ao esgotamento dos nossos recursos. Estes s\u00e3o alguns dos principais eixos de mudan\u00e7a que tamb\u00e9m representam os maiores desafios para a humanidade no in\u00edcio do s\u00e9culo XXI.<\/em><\/td><\/tr><tr><td>Projetos individuais: <strong>Alberto Giuliani<\/strong> (It\u00e1lia), <strong>Pasha Kritchko<\/strong> (Bielorr\u00fassia), <strong>Mykhaylo Palinchak <\/strong>(Ucr\u00e2nia), <strong>Judit Ruprech<\/strong> (Hungria) e <strong>Simone Tramonte<\/strong> (It\u00e1lia).<br \/>Comiss\u00e1rio: <strong>Marta Szyma\u0144ska<\/strong><br \/>Coordenador: <strong>Radek Lipk<\/strong>a<br \/><em>Organizado pela CinEast em colabora\u00e7\u00e3o e com o apoio de <\/em><a href=\"https:\/\/www.neimenster.lu\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Neim\u00ebnster<\/em><\/a><em>.<\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Convidamo-lo(a) a visitar a exposi\u00e7\u00e3o \u00abAdaptations\u00bb na WED 4 de outubro [...]<\/p>","protected":false},"author":3,"featured_media":2991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-2989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-photo-expo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/2989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=2989"}],"version-history":[{"count":0,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/2989\/revisions"}],"wp:attachment":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=2989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=2989"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=2989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}