{"id":621,"date":"2012-03-27T07:51:07","date_gmt":"2012-03-27T05:51:07","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=621"},"modified":"2012-03-27T07:51:07","modified_gmt":"2012-03-27T05:51:07","slug":"exposition-paris-spotted-by-irma-kravcovaite-du-29-mars-au-15-avril-2012","status":"publish","type":"post","link":"http:\/\/english.ciel.lu\/pt\/exposition-paris-spotted-by-irma-kravcovaite-du-29-mars-au-15-avril-2012\/","title":{"rendered":"Exposi\u00e7\u00e3o \u00abParis spotted by Irma Kravcovaite\u00bb du 29 mars au 15 avril 2012"},"content":{"rendered":"<p>Notre membre Irma Kravcovaite exp\u00f5e ses photos de Paris \u00e0 la Cour de Justice de l\u2019UE au deuxi\u00e8me \u00e9tage de la gall\u00e9rie. L\u2019exposition durera du 29 mars au 15 avril 2012.<\/p>\n<p>Le vernissage aura lieu le jeudi 29 mars \u00e0s 17h30.<\/p>\n<p>Pour plus d\u2019infos ou si vous voulez venir au vernissage, vous pouvez contacter Irma directement sur le num\u00e9ro suivant: +352-621-761098.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-637\" title=\"IrmaExposi\u00e7\u00e3oParis\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/IrmaExhibitionParis1.jpg?resize=271%2C384\" alt=\"\" width=\"271\" height=\"384\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Notre membre Irma Kravcovaite expor ses fotos de Paris \u00e0 la Cour de Justice de [...]<\/p>","protected":false},"author":2,"featured_media":623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-expo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=621"}],"version-history":[{"count":0,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/621\/revisions"}],"wp:attachment":[{"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=621"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}