{"id":1261,"date":"2014-03-11T00:26:41","date_gmt":"2014-03-10T22:26:41","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=1261"},"modified":"2014-03-11T00:26:41","modified_gmt":"2014-03-10T22:26:41","slug":"nouvelle-galerie-pierre-cester-maho-beach-ile-de-saint-martin-partie-neerlandaise","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/de\/nouvelle-galerie-pierre-cester-maho-beach-ile-de-saint-martin-partie-neerlandaise\/","title":{"rendered":"Nouvelle galerie: Pierre Cester \u2013 Maho-Beach \u2013 Ile de Saint Martin (partie n\u00e9erlandaise)"},"content":{"rendered":"<blockquote><p>L\u2019\u00eele de Saint-Martin aux Antilles est r\u00e9put\u00e9e pour ses 32 plages au sable fin, mais l\u2019une d\u2019entre elles, Maho Beach, est particuli\u00e8re pour les atterrissages spectaculaires d\u2019avions de ligne arrivant \u00e0 l\u2019a\u00e9roport international \u201ePrincess Juliana\u201c, cette plage se trouvant \u00e0 quelques dizaines m\u00e8tres seulement du seuil de piste.<br \/>\nIl faut observer les touristes les yeux braqu\u00e9s sur le ciel, appareils Fotos, smartphones oder tablettes \u00e0 bout de bras!<br \/>\nPour eux, le jeu consiste \u00e0 photographier leur compagne ou compagnon au moment pr\u00e9cis o\u00f9 l\u2019avion passe au-dessus de leur t\u00eate. Pas si facile, un avion de ligne atterri \u00e0 une vitesse d\u2019environ 280 km\/h...<\/p>\n<p>Pour ma part, j\u2019ai essay\u00e9 de capter quelques une de ces sc\u00e8nes et je vous en suggest un petit \u00e9chantillon.<\/p><\/blockquote>\n<p>Pierre Cester<\/p>\n<p>[Nggallery-ID = 28]<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00eele de Saint-Martin aux Antilles est r\u00e9put\u00e9e pour ses 32 plages au sable fin, mais [...]<\/p>","protected":false},"author":4,"featured_media":1302,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[78,89,162,164],"class_list":["post-1261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-gallery","tag-galerie","tag-images","tag-photos","tag-pierre-cester"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/1261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/comments?post=1261"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/1261\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/media?parent=1261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/categories?post=1261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/tags?post=1261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}