{"id":2380,"date":"2022-02-08T22:59:42","date_gmt":"2022-02-08T20:59:42","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=2380"},"modified":"2022-02-08T22:59:42","modified_gmt":"2022-02-08T20:59:42","slug":"les-plus-beaux-villages","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/de\/les-plus-beaux-villages\/","title":{"rendered":"Les plus beaux d\u00f6rfer..."},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"alignleft\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/Screenshot-2022-02-08-at-19.12.16-1.png?w=640\" alt=\"\" class=\"wp-image-2372\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Fotowettbewerb rund um die belgischen D\u00f6rfer Chassepierre, Torgny und Nobressart, alle innerhalb einer Stunde oder so von Luxemburg. Mehr Details <a href=\"https:\/\/beauxvillages.be\/concours-de-photos-artistiques\/\">hier<\/a>. Einreichungsfrist: 28. Februar 2022.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein Fotowettbewerb rund um die belgischen D\u00f6rfer Chassepierre, Torgny und Nobressart, alle innerhalb [...]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3,7],"tags":[],"class_list":["post-2380","post","type-post","status-publish","format-standard","hentry","category-blog","category-concours","category-photo-news"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/2380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/comments?post=2380"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/2380\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/media?parent=2380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/categories?post=2380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/tags?post=2380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}