{"id":2989,"date":"2023-09-28T19:46:46","date_gmt":"2023-09-28T17:46:46","guid":{"rendered":"https:\/\/www.ciel.lu\/?p=2989"},"modified":"2023-09-28T19:46:46","modified_gmt":"2023-09-28T17:46:46","slug":"exhibition-adaptations-organised-by-cineast","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/de\/exhibition-adaptations-organised-by-cineast\/","title":{"rendered":"Expo: \u201eAnpassungen\u201c organisiert von CinEast"},"content":{"rendered":"<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Wir laden Sie herzlich zur Vernissage der Ausstellung \u201e<strong>Anpassungen\u201c<\/strong> auf <strong>MI 4 OKTOBER um 18.30 Uhr<\/strong> (<em>Freier Eintritt<\/em>)<\/td><\/tr><tr><td><img data-recalc-dims=\"1\" decoding=\"async\"   alt=\"\" src=\"https:\/\/i0.wp.com\/mcusercontent.com\/373994ade2001bf8284e937f5\/images\/623fc7a6-c4ec-fcf2-5462-fba4679ecae9.jpg?w=564&#038;ssl=1\"\/><\/td><\/tr><tr><td>Die Fotoausstellung \u201e<strong>Anpassungen<\/strong>\u2019 pr\u00e4sentiert in den Salles vout\u00e9es in Neim\u00ebnster eine visuelle Reflexion \u00fcber das Hauptthema des Festivals und untersucht die tiefgreifenden Anpassungen, die durch einige der bedeutendsten Ver\u00e4nderungen erforderlich sind, mit denen unsere Gesellschaften und die Menschheit derzeit konfrontiert sind.<br \/>Anpassung an die Folgen des derzeitigen Krieges in der Ukraine, nat\u00fcrlich an die massiven und vielf\u00e4ltigen Herausforderungen des Klimawandels, aber auch an ein Umfeld, das von zunehmenden Migrationen und schnellen technologischen Entwicklungen gepr\u00e4gt ist.<br \/>Eine der Perspektiven, die den Kurator leitete, <strong>Marta Szyma\u0144ska<\/strong>, Bei ihrer Wahl der fotografischen Projekte sollte sie sich Anpassungen nicht nur als erzwungene Ver\u00e4nderungen durch eine gro\u00dfe Herausforderung vorstellen, sondern \u2013 zumindest in einigen F\u00e4llen \u2013 auch als kreative L\u00f6sungen f\u00fcr neue Umst\u00e4nde, die uns vorantreiben.<br \/><em>In der Vergangenheit musste sich die Menschheit nur sehr selten an radikale Ver\u00e4nderungen innerhalb eines einzigen Lebens oder sogar einer Generation anpassen. Es besteht kein Zweifel, dass wir derzeit in vielen Bereichen eine beispiellose Ver\u00e4nderungsrate erleben, die sich unumkehrbar auf die Welt, die wir kennen, und auf die Art und Weise auswirkt, wie wir es gewohnt sind, damit umzugehen. Diese Methoden sind nicht mehr wirksam oder v\u00f6llig veraltet. Die F\u00e4higkeit, sich an solche sich schnell ver\u00e4ndernden Bedingungen anzupassen, scheint eines der wichtigsten, wenn nicht sogar das wichtigste menschliche Merkmal sowohl f\u00fcr Einzelpersonen als auch f\u00fcr Gesellschaften zu sein. Die unumkehrbaren Auswirkungen des Klimawandels, des demografischen Wandels, einschlie\u00dflich Migration und einer alternden Bev\u00f6lkerung, Krieg, Menschenrechtsverletzungen, technologische Revolution, einschlie\u00dflich k\u00fcnstlicher Intelligenz, und ihre Auswirkungen auf den Arbeitsmarkt, autokratische Regierungen und die Ideologie des st\u00e4ndigen Wachstums, die zur Ersch\u00f6pfung unserer Ressourcen f\u00fchrt. Dies sind einige der Hauptachsen des Wandels, die zu Beginn des 21. Jahrhunderts auch die gr\u00f6\u00dften Herausforderungen f\u00fcr die Menschheit darstellen.<\/em><\/td><\/tr><tr><td>Einzelprojekte: <strong>Alberto Giuliani<\/strong> (Italien), <strong>Pascha Kritchko<\/strong> (Wei\u00dfrussland), <strong>Mykhaylo Palinchak <\/strong>(Ukraine), <strong>Judit Ruprech<\/strong> (Ungarn) und <strong>Simone Tramonte<\/strong> (Italien).<br \/>Auftraggeber: <strong>Marta Szyma\u0144ska<\/strong><br \/>Koordinator: <strong>Radek Lipk<\/strong>a<br \/><em>Organisiert von CinEast in Zusammenarbeit und mit Unterst\u00fctzung von <\/em><a href=\"https:\/\/www.neimenster.lu\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Neim\u00ebnster<\/em><\/a><em>.<\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Wir laden Sie herzlich zur Vernissage der Ausstellung \u201eAdaptations\u201c am 4. OKTOBER ein [...]<\/p>","protected":false},"author":3,"featured_media":2991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-2989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-photo-expo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/2989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/comments?post=2989"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/2989\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/media?parent=2989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/categories?post=2989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/tags?post=2989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}