{"id":430,"date":"2012-01-27T05:22:58","date_gmt":"2012-01-27T03:22:58","guid":{"rendered":"http:\/\/www.ciel.lu\/new_ciel\/?p=430"},"modified":"2012-01-27T05:22:58","modified_gmt":"2012-01-27T03:22:58","slug":"jean-marc-rohmer-dans-reponses-photo-239-japon-apres-fukushima","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/de\/jean-marc-rohmer-dans-reponses-photo-239-japon-apres-fukushima\/","title":{"rendered":"Jean-Marc Rohmer dans R\u00e9ponses Foto 239 \u2013 Japon, l\u2019apr\u00e8s Fukushima"},"content":{"rendered":"<p style=\"text-align: left;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-431 alignleft\" title=\"Reponses-Foto-239\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/reponses-photo-239-270x360.jpg?resize=270%2C360\" alt=\"\" width=\"270\" height=\"360\" \/>Jean-Marc Rohmer, notre ma\u00eetre du stage d\u2019introduction \u00e0 la photographie en fran\u00e7ais, figure avec un reportage sur <em>Japon, l\u2019apr\u00e8s Fukushima<\/em> dans le num\u00e9ro 239 de la revue R\u00e9ponses Foto! Fotos en N&amp;B spectaculaires sans pr\u00e9sence humaine, montrent la dimension de cette disaster. Interview\u00e9 par Sylvie Hugues, Jean-Marc raconte comment il y a eu l\u2019opportunit\u00e9 d\u2019aller faire ce reportage, son approche, choix technique, etc. Un num\u00e9ro \u00e0 ne pas manquer! gepostet Vor mehr als einem Jahr<\/p>","protected":false},"excerpt":{"rendered":"<p>Jean-Marc Rohmer, notre ma\u00eetre du stage d\u2019introduction \u00e0 la photographie en fran\u00e7ais, figure avec un [...]<\/p>","protected":false},"author":2,"featured_media":431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[77,94,100,103,174,175,176],"class_list":["post-430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-news","tag-fukushima","tag-interview","tag-japon","tag-jean-marc-rohmer","tag-reponses-photo","tag-reportage","tag-revue"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/posts\/430\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/media?parent=430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/categories?post=430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/de\/wp-json\/wp\/v2\/tags?post=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}