{"id":2265,"date":"2019-10-17T11:37:02","date_gmt":"2019-10-17T09:37:02","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=2265"},"modified":"2019-10-17T11:37:02","modified_gmt":"2019-10-17T09:37:02","slug":"exposition-ombres-et-lumieres","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/it\/exposition-ombres-et-lumieres\/","title":{"rendered":"Esposizione \"Ombres et lumi\u00e8res\""},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le Club photo des Institutions Europ\u00e9ennes \u00e0 Luxembourg (CIEL) et la Repr\u00e9sentation de la Commission europ\u00e9enne au Luxembourg ont le plaisir de vous inviter au vernissage de l'exposition de photos <strong>Ombres et lumi\u00e8res<\/strong>, le lundi 21 octobre 2019 \u00e0 17h30 \u00e0 la Maison de l'Europe \u2013 Centre d'information europ\u00e9en.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/ombres_et_lumieres_21_oct_20191.png?w=640\" alt=\"\" class=\"wp-image-2267\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Fotografo, c\u2019est \u00e9crire avec la lumi\u00e8re. Ma\u00eetriser la lumi\u00e8re, c\u2019est la base de la technique photographique. Mais lorsqu\u2019on begin \u00e0 jouer avec la lumi\u00e8re et les ombres, on quitte le domaine de la technique pour arriver dans celui de l\u2019art. Ce sont \u00e0 ces jeux d\u2019ombres et de lumi\u00e8re que se sont essay\u00e9s les photographes du Cercle culturel des institutions \u00e0 Luxembourg. Ritratti, paghe, street photography, peu importe le sujet, seule compte l'harmonie, mise encore plus en valeur par le choix du noir et blanc.<\/em><br \/>\n20 fotografie, 20 interpr\u00e9tations<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci de vous inscrire envoyant un email \u00e0 l'adresse suivante : <a href=\"mailto:comm-rep-lux@ec.europa.eu\">comm-rep-lux@ec.europa.eu<\/a> ou par t\u00e9l\u00e9phone au (+352) 430 134 925<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'exposition est ouverte au public \u00e0 partir du 21 octobre 2019.<br \/>\nLundi 13h00-17h00 \u2013 Mardi au vendredi 9h00-18h00 \u2013 Samedi 12h00-16h00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Maison de l'Europe \u2013 Centre d'information europ\u00e9en (Centro d'informazione europeo)<\/strong><br \/>\n7, rue du March\u00e9-aux-Herbes<br \/>\nL-1728 Lussemburgo<\/p>","protected":false},"excerpt":{"rendered":"<p>Le Club photo des Institutions Europ\u00e9ennes \u00e0 Luxembourg (CIEL) et la Repr\u00e9sentation de la Commission [...]<\/p>","protected":false},"author":4,"featured_media":2267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[43,65,116,147,195],"class_list":["post-2265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-expo","tag-ciel","tag-exposition","tag-maison-de-leurope","tag-ombres-et-lumieres","tag-vernissage"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts\/2265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/comments?post=2265"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/posts\/2265\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/media?parent=2265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/categories?post=2265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/it\/wp-json\/wp\/v2\/tags?post=2265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}