{"id":1241,"date":"2014-02-25T12:00:45","date_gmt":"2014-02-25T10:00:45","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=1241"},"modified":"2014-02-25T12:00:45","modified_gmt":"2014-02-25T10:00:45","slug":"exposition-de-myriam-barbara-ziade-hymne-a-la-beaute-a-walferdange","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/pt\/exposition-de-myriam-barbara-ziade-hymne-a-la-beaute-a-walferdange\/","title":{"rendered":"Exposi\u00e7\u00e3o de Myriam Barbara-Ziad\u00e9 \u00abHymne \u00e0 la beaut\u00e9\u00bb \u00e0 Walferdange"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/hymne.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/hymne.png?resize=600%2C275\" alt=\"Hymne \u00e0 la beaut\u00e9\" width=\"600\" height=\"275\" class=\"size-full wp-image-1243\" \/><\/a><br \/>\nApr\u00e8s les expositions au Domaine Thermal de Mondorf et \u00e0 l\u2019Espace Royal-Monterey \u00e0 Luxembourg, l\u2019exposition photographique de notre membre Myriam Barbara-Ziad\u00e9 \u201cHymne \u00e0 la Beaut\u00e9\u201d revient \u00e0 la Ville de Walferdange. L\u2019exposition aura lieu les week-ends du 1er et 2, et du 8 et 9 mars 2014 \u00e0 la Maison Dufaing \u00e0 Walferdange (Place des Martyrs \u2013 Rond-point \u00e0 c\u00f4t\u00e9 de l\u2019h\u00f4tel Moris).<\/p>\n<p>Le vernissage aura lieu le vendredi 28 f\u00e9vrier 2014 \u00e0s 18h00. Vous y \u00eates cordialement invit\u00e9s.<\/p>\n<p>Myriam nous montre 15 retratos de personnes touch\u00e9es par le cancer du sein.<\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s les expositions au Domaine Thermal de Mondorf et \u00e0 l\u2019Espace Royal-Monterey \u00e0 Luxembourg, l\u2019exposition [...]<\/p>","protected":false},"author":4,"featured_media":1243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[65,140],"class_list":["post-1241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-expo","tag-exposition","tag-myriam-barbara-ziade"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/1241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=1241"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/1241\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=1241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=1241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=1241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}