{"id":1253,"date":"2014-03-08T19:32:37","date_gmt":"2014-03-08T17:32:37","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=1253"},"modified":"2014-03-08T19:32:37","modified_gmt":"2014-03-08T17:32:37","slug":"sortie-parcours-dartistes-a-metz-f-le-dimanche-16-mars-2014","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/pt\/sortie-parcours-dartistes-a-metz-f-le-dimanche-16-mars-2014\/","title":{"rendered":"Sortie \u201cParcours d\u2019artistes\u201d \u00e0 Metz (F) le dimanche 16 de mar\u00e7o de 2014"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/post1.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/post1.png?resize=300%2C399\" alt=\"publica\u00e7\u00e3o\" width=\"300\" height=\"399\" class=\"aligncenter size-full wp-image-1255\" \/><\/a><br \/>\nPour la sixi\u00e8me ann\u00e9e cons\u00e9cutive, la ville de Metz accueille la manifestation<em>Parcours d\u2019artistes<\/em>\u201d les 15 et 16 mars 2014.<\/p>\n<p>Le temps d\u2019un fim de semana, des ateliers, des lieux de production qui soutiennent les artistes locaux tout au long de l\u2019ann\u00e9e ouvrent leurs portes. Ainsi diff\u00e9rents artistes (peintres, graveurs, photographes, etc.) pr\u00e9sentent leurs travaux au centre ville et en p\u00e9riph\u00e9rie dans diff\u00e9rents lieux parfois insolites (ateliers, mus\u00e9es, appartements, caf\u00e9s, etc.).<\/p>\n<p>Cette ann\u00e9e, notre membre Myriam Barbara-Ziad\u00e9, pr\u00e9sente une nouvelle exposition intitul\u00e9e<strong>Olho de peixe \u2013 Olho de elefante<\/strong>\u201d (\u00e0 l\u2019\u00e9tape 7 du parcours).<br \/>\nCertains qu\u2019un tel \u00e9v\u00e9nement photog\u00e9nique int\u00e9ressera nos membres, nous organisons une sortie le dimanche 16 de mar\u00e7o de 2014.<\/p>\n<p>Despeje mais informa\u00e7\u00f5es, visitez le site de l\u2019\u00e9v\u00e9nement : <a href=\"http:\/\/parcoursdartistes.org\/\" title=\"Parcours d&#039;artistes\" target=\"_blank\" rel=\"noopener\">http:\/\/parcoursdartistes.org\/<\/a> ou consultez le <a href=\"http:\/\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/depliant-PARCOURS-2014-.pdf\">PARCOURS DESEMPENHADOS 2014<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pour la sixi\u00e8me ann\u00e9e cons\u00e9cutive, la ville de Metz accueille la manifestation \u201cParcours d\u2019artistes\u201d les [...]<\/p>","protected":false},"author":4,"featured_media":1255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[128,140,185],"class_list":["post-1253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club-news","tag-metz","tag-myriam-barbara-ziade","tag-sortie"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/1253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/1253\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=1253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=1253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}