{"id":1559,"date":"2015-03-16T08:42:14","date_gmt":"2015-03-16T06:42:14","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=1559"},"modified":"2015-03-16T08:42:14","modified_gmt":"2015-03-16T06:42:14","slug":"parcours-dartistes-a-metz-f-21-et-22-mars-2015","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/pt\/parcours-dartistes-a-metz-f-21-et-22-mars-2015\/","title":{"rendered":"\u00abParcours d\u2019artistes\u00bb \u00e0 Metz (F) \u2013 21 e 22 de mar\u00e7o de 2015"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1255\" alt=\"publica\u00e7\u00e3o\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/parcours15.jpg?resize=300%2C399\" width=\"300\" height=\"399\" \/><\/p>\n<p>Pour la septi\u00e8me ann\u00e9e cons\u00e9cutive, la ville de Metz (Fran\u00e7a) accueille la manifestation \u201c<em>Parcours d\u2019artistes<\/em>\u201d les 21 e 22 de mar\u00e7o de 2015.<\/p>\n<p>Le temps d\u2019un fim de semana, des ateliers, des lieux de production qui soutiennent les artistes locaux tout au long de l\u2019ann\u00e9e ouvrent leurs portes. Ainsi diff\u00e9rents artistes (peintres, graveurs, photographes, etc.) pr\u00e9sentent leurs travaux au centre ville et en p\u00e9riph\u00e9rie dans diff\u00e9rents lieux parfois insolites (ateliers, mus\u00e9es, appartements, caf\u00e9s, etc.).<\/p>\n<p>Cette ann\u00e9e encore, notre membre Myriam Barbara-Ziad\u00e9, pr\u00e9sente une nouvelle exposition \u00e0 Lorry-l\u00e8s-Metz, Chez Alain Meyer (\u00e9tape 38 du parcours \u2013 69, Grand-Rue F-57050 Lorry-l\u00e8s-Metz).<\/p>\n<p>Despeje mais informa\u00e7\u00f5es, visitez le site de l\u2019\u00e9v\u00e9nement : <a title=\"Parcours d&#039;artistes\" href=\"http:\/\/parcoursdartistes.org\/\" target=\"_blank\" rel=\"noopener\">http:\/\/parcoursdartistes.org\/<\/a> ou consultez le <a href=\"http:\/\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/depliant-PARCOURS-2015.pdf\">PARCOURS DESEMPENHADOS 2015<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pour la septi\u00e8me ann\u00e9e cons\u00e9cutive, la ville de Metz (Fran\u00e7a) accueille la manifestation \u201cParcours d\u2019artistes\u201d [...]<\/p>","protected":false},"author":4,"featured_media":1564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[65,128,140],"class_list":["post-1559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-expo","tag-exposition","tag-metz","tag-myriam-barbara-ziade"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/1559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=1559"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/1559\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=1559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=1559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=1559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}