{"id":3475,"date":"2025-05-23T23:05:40","date_gmt":"2025-05-23T21:05:40","guid":{"rendered":"http:\/\/english.ciel.lu\/?p=3475"},"modified":"2025-05-27T11:39:20","modified_gmt":"2025-05-27T09:39:20","slug":"invitation-success","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/pt\/invitation-success\/","title":{"rendered":"Convite &amp; \u00eaxito"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O clube de fotografia CIEL tem muito orgulho em anunciar que <strong>Roc\u00edo Mart\u00edn Fr\u00edas<\/strong> Ganhou a medalha de ouro e <strong>Agn\u0117 Vaitkevi\u010di\u016bt\u0117<\/strong> a medalha de prata (assunto obrigat\u00f3rio \u00abIntera\u00e7\u00e3o com a \u00e1gua\u00bb) na 51.a exposi\u00e7\u00e3o nacional da Federa\u00e7\u00e3o Luxemburguesa de Fotografia Art\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venha descobrir as suas fotografias, juntamente com as outras 18 fotografias aceites dos membros do nosso clube, <strong>a 28 de Junho<\/strong>, <strong>a partir das 16h30m<\/strong> no Centro de Lazer Lamadelaine (encontrar\u00e1 todas as informa\u00e7\u00f5es \u00fateis no cart\u00e3o de convite abaixo).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/img_1627-1.png?w=1280&amp;ssl=1\" alt=\"\"\/><\/figure>","protected":false},"excerpt":{"rendered":"<p>O clube de fotografia CIEL tem muito orgulho em anunciar que Roc\u00edo Mart\u00edn Fr\u00edas venceu a [...]<\/p>","protected":false},"author":1,"featured_media":3484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,4,8],"tags":[65,221,197],"class_list":["post-3475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-photo-expo","category-club-news","tag-exposition","tag-success","tag-vie-du-club"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/english.ciel.lu\/wp-content\/uploads\/2025\/05\/img_1627-1.webp?fit=768%2C384&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/3475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=3475"}],"version-history":[{"count":2,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/3475\/revisions"}],"predecessor-version":[{"id":3477,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/3475\/revisions\/3477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media\/3484"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=3475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=3475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=3475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}