{"id":882,"date":"2012-11-23T22:38:28","date_gmt":"2012-11-23T20:38:28","guid":{"rendered":"http:\/\/www.ciel.lu\/?p=882"},"modified":"2012-11-23T22:38:28","modified_gmt":"2012-11-23T20:38:28","slug":"vincenzo-cardile-expose-au-batiment-jmo","status":"publish","type":"post","link":"https:\/\/english.ciel.lu\/pt\/vincenzo-cardile-expose-au-batiment-jmo\/","title":{"rendered":"Vincenzo Cardile expor au b\u00e2timent JMO"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/Vincenzo_RegardsAfrique.jpg\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-908\" title=\"Vincenzo_RegardsAfrique_600px\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/Vincenzo_RegardsAfrique_600px.jpg?resize=600%2C440\" alt=\"\" width=\"600\" height=\"440\" \/><\/a><\/p>\n<p>Notre membre Vincenzo Cardile expor au b\u00e2timent Jean-Monnet (JMO) de la Commission europ\u00e9enne \u00e0 Luxembourg jusqu\u2019au 21 d\u00e9cembre 2012. Le vernissage aura lieu le 4 d\u00e9cembre \u00e0 18h00.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/VincenzoCardile_JMO-01.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-886\" title=\"VincenzoCardile_JMO-01\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/VincenzoCardile_JMO-01.jpg?resize=600%2C208\" alt=\"\" width=\"600\" height=\"208\" \/><\/a><\/p>\n<blockquote><p>Au plaisir de vous accueillir au vernissage du photographe Vincenzo Cardile, qui vous pr\u00e9sentera, dans des pr\u00e9cieuses reprodu\u00e7\u00f5es, une s\u00e9rie de portraits in\u00e9dits, r\u00e9alis\u00e9s au Mali.<br \/>\nVincenzo Cardile a su mettre en valeur la beaut\u00e9 naturelle de ces hommes et de ces femmes, \u00e9leveurs Peuls ou chasseurs Malink\u00e9, en capter le regard, gage d\u2019\u00e9change et d\u2019amiti\u00e9 entre \u201cici\u201d et \u201cl\u00e0-bas\u201d, de ce dialogue n\u00e9cessaire entre \u201cNord\u201d et \u201cSud\u201d que nous devrions nous efforcer d\u2019entretenir entre nous tous, simplement \u00eatres humains. Certains de ces portraits constituent d\u00e9sormais le t\u00e9moignage rare d\u2019une r\u00e9alit\u00e9 malheureusement boulevers\u00e9e par les \u00e9v\u00e9nements qui traversent actuellement le Mali. Nous esp\u00e9rons vous y voir nombreux.<\/p><\/blockquote>\n<p><a href=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/VincenzoCardile_JMO-02.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-887\" title=\"VincenzoCardile_JMO-02\" src=\"https:\/\/i0.wp.com\/www.ciel.lu\/new_ciel\/wp-content\/uploads\/VincenzoCardile_JMO-02.jpg?resize=600%2C387\" alt=\"\" width=\"600\" height=\"387\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Notre membre Vincenzo Cardile expor au b\u00e2timent Jean-Monnet (JMO) de la Commission europ\u00e9enne \u00e0 Luxembourg [...]<\/p>","protected":false},"author":2,"featured_media":887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[65,105,200],"class_list":["post-882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo-expo","tag-exposition","tag-jmo","tag-vincenzo-cardile"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/comments?post=882"}],"version-history":[{"count":0,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/posts\/882\/revisions"}],"wp:attachment":[{"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/media?parent=882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/categories?post=882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english.ciel.lu\/pt\/wp-json\/wp\/v2\/tags?post=882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}